{"id":16,"count":47,"description":"","link":"https:\/\/perapalace.com\/en\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uncategorized ar\u015fivleri - Pera Palace Hotel<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncategorized ar\u015fivleri - Pera Palace Hotel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perapalace.com\/en\/category\/uncategorized\/\" \/>\n<meta property=\"og:site_name\" content=\"Pera Palace Hotel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/perapalace.com\\\/en\\\/category\\\/uncategorized\\\/\",\"url\":\"https:\\\/\\\/perapalace.com\\\/en\\\/category\\\/uncategorized\\\/\",\"name\":\"Uncategorized ar\u015fivleri - Pera Palace Hotel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perapalace.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perapalace.com\\\/en\\\/category\\\/uncategorized\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perapalace.com\\\/en\\\/category\\\/uncategorized\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/perapalace.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perapalace.com\\\/#website\",\"url\":\"https:\\\/\\\/perapalace.com\\\/\",\"name\":\"Pera Palace Hotel\",\"description\":\"\u0130konik ve Tarihi Otel - \u0130stanbul&#039;un Kalbi Pera&#039;da\",\"publisher\":{\"@id\":\"https:\\\/\\\/perapalace.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perapalace.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perapalace.com\\\/#organization\",\"name\":\"Pera Palace Hotel\",\"url\":\"https:\\\/\\\/perapalace.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/perapalace.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perapalace.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/main-logo.svg\",\"contentUrl\":\"https:\\\/\\\/perapalace.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/main-logo.svg\",\"width\":120,\"height\":97,\"caption\":\"Pera Palace Hotel\"},\"image\":{\"@id\":\"https:\\\/\\\/perapalace.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/perapalacehotel\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uncategorized ar\u015fivleri - Pera Palace Hotel","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Uncategorized ar\u015fivleri - Pera Palace Hotel","og_url":"https:\/\/perapalace.com\/en\/category\/uncategorized\/","og_site_name":"Pera Palace Hotel","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/perapalace.com\/en\/category\/uncategorized\/","url":"https:\/\/perapalace.com\/en\/category\/uncategorized\/","name":"Uncategorized ar\u015fivleri - Pera Palace Hotel","isPartOf":{"@id":"https:\/\/perapalace.com\/#website"},"breadcrumb":{"@id":"https:\/\/perapalace.com\/en\/category\/uncategorized\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/perapalace.com\/en\/category\/uncategorized\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/perapalace.com\/en\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"https:\/\/perapalace.com\/#website","url":"https:\/\/perapalace.com\/","name":"Pera Palace Hotel","description":"\u0130konik ve Tarihi Otel - \u0130stanbul&#039;un Kalbi Pera&#039;da","publisher":{"@id":"https:\/\/perapalace.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perapalace.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/perapalace.com\/#organization","name":"Pera Palace Hotel","url":"https:\/\/perapalace.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/perapalace.com\/#\/schema\/logo\/image\/","url":"https:\/\/perapalace.com\/wp-content\/uploads\/2021\/12\/main-logo.svg","contentUrl":"https:\/\/perapalace.com\/wp-content\/uploads\/2021\/12\/main-logo.svg","width":120,"height":97,"caption":"Pera Palace Hotel"},"image":{"@id":"https:\/\/perapalace.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/perapalacehotel"]}]}},"_links":{"self":[{"href":"https:\/\/perapalace.com\/en\/wp-json\/wp\/v2\/categories\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perapalace.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/perapalace.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/perapalace.com\/en\/wp-json\/wp\/v2\/posts?categories=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}